{"id":8715,"date":"2024-09-03T14:41:03","date_gmt":"2024-09-03T19:41:03","guid":{"rendered":"https:\/\/cooperacion.unmsm.edu.pe\/?p=8715"},"modified":"2024-09-24T14:41:45","modified_gmt":"2024-09-24T19:41:45","slug":"ceremonia-de-bienvenida-a-becarios-de-alianza-del-pacifico","status":"publish","type":"post","link":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/2024\/09\/03\/ceremonia-de-bienvenida-a-becarios-de-alianza-del-pacifico\/","title":{"rendered":"Ceremonia de Bienvenida a Becarios de Alianza del Pacifico"},"content":{"rendered":"\n<p>La Oficina General de Cooperaci\u00f3n y Relaciones Interinstitucionales de la Universidad Nacional Mayor de San Marcos, presente en Ceremonia de Bienvenida a Becarios de Alianza del Pacifico.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udc49\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t51\/1\/16\/1f449.png\">En este semestre 2024-II, dos becarios de Universidades de Colombia seguir\u00e1n estudios en nuestra Universidad.<\/p>\n\n\n\n<p>Bienvenidos a la UNMSM! <img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udc4f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tfe\/1\/16\/1f44f.png\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"536\" src=\"https:\/\/cooperacion.unmsm.edu.pe\/wp-content\/uploads\/2024\/09\/458193032_915935860574989_6593542354315818630_n-1024x536.jpg\" alt=\"\" class=\"wp-image-8716\" srcset=\"https:\/\/cooperacion.unmsm.edu.pe\/wp-content\/uploads\/2024\/09\/458193032_915935860574989_6593542354315818630_n-1024x536.jpg 1024w, https:\/\/cooperacion.unmsm.edu.pe\/wp-content\/uploads\/2024\/09\/458193032_915935860574989_6593542354315818630_n-300x157.jpg 300w, https:\/\/cooperacion.unmsm.edu.pe\/wp-content\/uploads\/2024\/09\/458193032_915935860574989_6593542354315818630_n-768x402.jpg 768w, https:\/\/cooperacion.unmsm.edu.pe\/wp-content\/uploads\/2024\/09\/458193032_915935860574989_6593542354315818630_n.jpg 1375w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Oficina General de Cooperaci\u00f3n y Relaciones Interinstitucionales de la Universidad Nacional Mayor de San Marcos, presente en Ceremonia de Bienvenida a Becarios de Alianza del Pacifico. En este semestre 2024-II, dos becarios de Universidades de Colombia seguir\u00e1n estudios en nuestra Universidad. Bienvenidos a la UNMSM!<\/p>\n","protected":false},"author":3,"featured_media":8717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8715"}],"collection":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/comments?post=8715"}],"version-history":[{"count":1,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8715\/revisions"}],"predecessor-version":[{"id":8718,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8715\/revisions\/8718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/media\/8717"}],"wp:attachment":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/media?parent=8715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/categories?post=8715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/tags?post=8715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}