{"id":8633,"date":"2024-07-30T14:14:00","date_gmt":"2024-07-30T19:14:00","guid":{"rendered":"https:\/\/cooperacion.unmsm.edu.pe\/?p=8633"},"modified":"2024-08-05T08:15:50","modified_gmt":"2024-08-05T13:15:50","slug":"evidencia-que-impulsa-el-cambio","status":"publish","type":"post","link":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/2024\/07\/30\/evidencia-que-impulsa-el-cambio\/","title":{"rendered":"Evidencia que Impulsa el Cambio"},"content":{"rendered":"\n<p>La Oficina General de Cooperaci\u00f3n y Relaciones Interinstitucionales &#8211; OGCRI de la Universidad Nacional Mayor de San Marcos, participa en el evento de cierre \u00abEvidencia que Impulsa el Cambio\u00bb auspiciado por la Agencia de EE.UU para el Desarrollo Internacional (USAID).<br>El intercambio de experiencias, conocimientos y perspectivas que se gener\u00f3 durante el evento enriqueci\u00f3 enormemente nuestras discusiones sobre el uso de la evidencia en las iniciativas de desarrollo y su papel crucial en la toma de decisiones informadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Oficina General de Cooperaci\u00f3n y Relaciones Interinstitucionales &#8211; OGCRI de la Universidad Nacional Mayor de San Marcos, participa en el evento de cierre \u00abEvidencia que Impulsa el Cambio\u00bb auspiciado por la Agencia de EE.UU para el Desarrollo Internacional (USAID).El intercambio de experiencias, conocimientos y perspectivas que se gener\u00f3 durante el evento enriqueci\u00f3 enormemente nuestras [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8633"}],"collection":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/comments?post=8633"}],"version-history":[{"count":1,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8633\/revisions"}],"predecessor-version":[{"id":8635,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8633\/revisions\/8635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/media\/8634"}],"wp:attachment":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/media?parent=8633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/categories?post=8633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/tags?post=8633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}