{"id":8630,"date":"2024-07-30T14:13:00","date_gmt":"2024-07-30T19:13:00","guid":{"rendered":"https:\/\/cooperacion.unmsm.edu.pe\/?p=8630"},"modified":"2024-08-05T08:14:42","modified_gmt":"2024-08-05T13:14:42","slug":"programa-move-la-america-2025-1","status":"publish","type":"post","link":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/2024\/07\/30\/programa-move-la-america-2025-1\/","title":{"rendered":"Programa: Move La Am\u00e9rica 2025.1"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" src=\"https:\/\/z-p3-static.xx.fbcdn.net\/images\/emoji.php\/v9\/t51\/1\/16\/1f449.png\" alt=\"\ud83d\udc49\">Es con gran satisfacci\u00f3n que les informamos que la Escuela Bahiana de Medicina y Salud P\u00fablica (Salvador, Bahia, Brasil) participa del Edital CAPES 07\/2024.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udc49\" src=\"https:\/\/z-p3-static.xx.fbcdn.net\/images\/emoji.php\/v9\/t51\/1\/16\/1f449.png\">El edital est\u00e1 ofreciendo 8 becas para estudiantes de maestr\u00eda o doctorado de Latinoam\u00e9rica y el Caribe, con el prop\u00f3sito de apoyar la realizaci\u00f3n de pr\u00e1cticas, investigaciones, actividades de extensi\u00f3n y, eventualmente, permitir la posibilidad de cursar asignaturas en programas de posgrado en la Escuela Bahiana.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udc49\" src=\"https:\/\/z-p3-static.xx.fbcdn.net\/images\/emoji.php\/v9\/t51\/1\/16\/1f449.png\">Las inscripciones deben realizarse directamente a trav\u00e9s de la p\u00e1gina del CAPES (Move La Am\u00e9rica), organismo del gobierno federal (Brasil).<br><img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udc49\" src=\"https:\/\/z-p3-static.xx.fbcdn.net\/images\/emoji.php\/v9\/t51\/1\/16\/1f449.png\">Plazo de inscripci\u00f3n: 08\/08\/2024 antes de las 17 horas ( hora de Bras\u00edlia)&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es con gran satisfacci\u00f3n que les informamos que la Escuela Bahiana de Medicina y Salud P\u00fablica (Salvador, Bahia, Brasil) participa del Edital CAPES 07\/2024. El edital est\u00e1 ofreciendo 8 becas para estudiantes de maestr\u00eda o doctorado de Latinoam\u00e9rica y el Caribe, con el prop\u00f3sito de apoyar la realizaci\u00f3n de pr\u00e1cticas, investigaciones, actividades de extensi\u00f3n y, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8630"}],"collection":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/comments?post=8630"}],"version-history":[{"count":1,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8630\/revisions"}],"predecessor-version":[{"id":8632,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/posts\/8630\/revisions\/8632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/media\/8631"}],"wp:attachment":[{"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/media?parent=8630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/categories?post=8630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cooperacion.unmsm.edu.pe\/index.php\/wp-json\/wp\/v2\/tags?post=8630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}